{"id":2312,"date":"2024-07-15T18:43:54","date_gmt":"2024-07-15T18:43:54","guid":{"rendered":"https:\/\/sustainabloom.org\/?post_type=external-link&#038;p=2312"},"modified":"2024-07-15T19:11:05","modified_gmt":"2024-07-15T19:11:05","slug":"el-reto-de-los-contenedores","status":"publish","type":"external-link","link":"https:\/\/sustainabloom.org\/es\/external-link\/the-container-challenge","title":{"rendered":"El reto del contenedor"},"template":"","link-categories":[72,62],"class_list":["post-2312","external-link","type-external-link","status-publish","hentry","link-categories-latest-industry-news","link-categories-plastics"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Container Challenge - Sustainabloom<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sustainabloom.org\/es\/enlace-externo\/el-reto-de-los-contenedores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Container Challenge - Sustainabloom\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sustainabloom.org\/es\/enlace-externo\/el-reto-de-los-contenedores\/\" \/>\n<meta property=\"og:site_name\" content=\"Sustainabloom\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-15T19:11:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sustainabloom.org\\\/external-link\\\/the-container-challenge\\\/\",\"url\":\"https:\\\/\\\/sustainabloom.org\\\/external-link\\\/the-container-challenge\\\/\",\"name\":\"The Container Challenge - Sustainabloom\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sustainabloom.org\\\/#website\"},\"datePublished\":\"2024-07-15T18:43:54+00:00\",\"dateModified\":\"2024-07-15T19:11:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sustainabloom.org\\\/external-link\\\/the-container-challenge\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sustainabloom.org\\\/external-link\\\/the-container-challenge\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sustainabloom.org\\\/external-link\\\/the-container-challenge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sustainabloom.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Container Challenge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sustainabloom.org\\\/#website\",\"url\":\"https:\\\/\\\/sustainabloom.org\\\/\",\"name\":\"Sustainabloom\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sustainabloom.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Container Challenge - Sustainabloom","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sustainabloom.org\/es\/enlace-externo\/el-reto-de-los-contenedores\/","og_locale":"es_ES","og_type":"article","og_title":"The Container Challenge - Sustainabloom","og_url":"https:\/\/sustainabloom.org\/es\/enlace-externo\/el-reto-de-los-contenedores\/","og_site_name":"Sustainabloom","article_modified_time":"2024-07-15T19:11:05+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sustainabloom.org\/external-link\/the-container-challenge\/","url":"https:\/\/sustainabloom.org\/external-link\/the-container-challenge\/","name":"The Container Challenge - Sustainabloom","isPartOf":{"@id":"https:\/\/sustainabloom.org\/#website"},"datePublished":"2024-07-15T18:43:54+00:00","dateModified":"2024-07-15T19:11:05+00:00","breadcrumb":{"@id":"https:\/\/sustainabloom.org\/external-link\/the-container-challenge\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sustainabloom.org\/external-link\/the-container-challenge\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sustainabloom.org\/external-link\/the-container-challenge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sustainabloom.org\/"},{"@type":"ListItem","position":2,"name":"The Container Challenge"}]},{"@type":"WebSite","@id":"https:\/\/sustainabloom.org\/#website","url":"https:\/\/sustainabloom.org\/","name":"Sustainabloom","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sustainabloom.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/sustainabloom.org\/es\/wp-json\/wp\/v2\/external-link\/2312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sustainabloom.org\/es\/wp-json\/wp\/v2\/external-link"}],"about":[{"href":"https:\/\/sustainabloom.org\/es\/wp-json\/wp\/v2\/types\/external-link"}],"wp:attachment":[{"href":"https:\/\/sustainabloom.org\/es\/wp-json\/wp\/v2\/media?parent=2312"}],"wp:term":[{"taxonomy":"link-categories","embeddable":true,"href":"https:\/\/sustainabloom.org\/es\/wp-json\/wp\/v2\/link-categories?post=2312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}