{"id":3996,"date":"2026-07-27T14:14:39","date_gmt":"2026-07-27T14:14:39","guid":{"rendered":"https:\/\/sustainabloom.org\/?post_type=news&#038;p=3996"},"modified":"2026-07-27T14:17:10","modified_gmt":"2026-07-27T14:17:10","slug":"nueva-plantilla-de-sustainabloom","status":"publish","type":"news","link":"https:\/\/sustainabloom.org\/es\/news\/new-sustainabloom-template","title":{"rendered":"La nueva plantilla de Sustainabloom ayuda a los productores de flores a planificar la sostenibilidad"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"607\" height=\"1024\" src=\"https:\/\/sustainabloom.org\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-23-at-2.15.11-PM-1-607x1024.png\" alt=\"\" class=\"wp-image-4003\" style=\"aspect-ratio:0.5923504098853283;width:272px;height:auto\" srcset=\"https:\/\/sustainabloom.org\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-23-at-2.15.11-PM-1-607x1024.png 607w, https:\/\/sustainabloom.org\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-23-at-2.15.11-PM-1-178x300.png 178w, https:\/\/sustainabloom.org\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-23-at-2.15.11-PM-1-768x1297.png 768w, https:\/\/sustainabloom.org\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-23-at-2.15.11-PM-1-540x912.png 540w, https:\/\/sustainabloom.org\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-23-at-2.15.11-PM-1.png 898w\" sizes=\"auto, (max-width: 607px) 100vw, 607px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Una nueva&nbsp;<a href=\"https:\/\/sustainabloom.org\/es\/plantillas-para-la-planificacion-de-la-sostenibilidad\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Plantilla de planificaci\u00f3n de la sostenibilidad<\/strong><\/a>&nbsp;para cultivadores de flores est\u00e1 disponible a trav\u00e9s de Sustainabloom, por parte de la&nbsp;<a href=\"http:\/\/endowment.org\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Fundaci\u00f3n Floral Americana&nbsp;<\/strong><\/a>(AFE). Este recurso gratuito ayuda a los agricultores a evaluar sus pr\u00e1cticas actuales y a elaborar un plan de sostenibilidad adaptado a su explotaci\u00f3n agr\u00edcola.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elaborada con la colaboraci\u00f3n de productores de flores, investigadores y socios del sector, la plantilla refleja las decisiones cotidianas que los productores toman en sus explotaciones. Tambi\u00e9n se ha elaborado a partir de conversaciones en todo el sector sobre la necesidad de contar con recursos pr\u00e1cticos que ayuden a las empresas a organizar sus iniciativas de sostenibilidad sin imponer un enfoque \u00fanico v\u00e1lido para todos.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u201cSabemos que los agricultores est\u00e1n muy ocupados y que la sostenibilidad puede parecerles una cosa m\u00e1s de la que preocuparse\u201d,\u201d<\/strong>&nbsp;afirm\u00f3 la Dra. Amanda Solliday, directora s\u00e9nior de Sustainabloom.&nbsp;<strong>\u201cNuestro objetivo era crear una herramienta que permitiera a los agricultores sentarse a reflexionar, identificar algunas prioridades y aprovechar el trabajo que ya est\u00e1n realizando\u201d.\u201d<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">La plantilla de planificaci\u00f3n abarca las principales \u00e1reas de la producci\u00f3n floral:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Flores<\/strong>: gesti\u00f3n de nutrientes y salud del suelo, gesti\u00f3n de plagas y enfermedades, sustratos, agua, envases, ampliaci\u00f3n y diversificaci\u00f3n de la temporada, pr\u00e1cticas poscosecha, certificaciones y comunicaci\u00f3n con los clientes.<\/li>\n\n\n\n<li><strong>Ubicaci\u00f3n<\/strong>: biodiversidad, edificios y comunidad.<\/li>\n\n\n\n<li><strong>Operaciones<\/strong>: suministro de energ\u00eda, iluminaci\u00f3n, transporte, maquinaria, gesti\u00f3n de la cadena de fr\u00edo y empleados.<\/li>\n\n\n\n<li><strong>Residuos<\/strong>: compostaje, reciclaje y reutilizaci\u00f3n.<\/li>\n\n\n\n<li><strong>Cadena de suministro<\/strong>: abastecimiento de materia prima vegetal, abastecimiento de otros insumos y comunicaci\u00f3n con los proveedores.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Cada secci\u00f3n comienza con una sencilla evaluaci\u00f3n tipo \u00absem\u00e1foro\u00bb que ayuda a los productores a evaluar sus pr\u00e1cticas actuales. A partir de ah\u00ed, la plantilla gu\u00eda a los usuarios a la hora de establecer objetivos, elegir medidas, asignar responsabilidades y realizar un seguimiento del progreso a lo largo del tiempo. El resultado es un plan que refleja las prioridades y los recursos de cada empresa.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u201cEsta plantilla resultar\u00e1 \u00fatil para muchos. Se trata de un recurso completo que ayudar\u00e1 a los productores a evaluar sus iniciativas actuales en materia de sostenibilidad e identificar formas pr\u00e1cticas de seguir mejorando\u201d,\u201d<\/strong>&nbsp;dijo Chris Schlegel, jefe de cultivo de D.S. Cole Growers en Loudon, Nuevo Hampshire.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">La plantilla se present\u00f3 en Cultivate\u201926, un importante encuentro para productores hort\u00edcolas organizado por AmericanHort, que tuvo lugar del 11 al 14 de julio en Columbus, Ohio. Los asistentes pudieron conocer mejor este nuevo recurso y c\u00f3mo puede ayudar a los productores de flores a dar pasos pr\u00e1cticos y cuantificables hacia la sostenibilidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta es la tercera plantilla de planificaci\u00f3n publicada por&nbsp;<a target=\"_blank\" href=\"https:\/\/sustainabloom.org\/es\/\" rel=\"noreferrer noopener\"><strong>Sustainabloom<\/strong><\/a>, que se suman a las plantillas para florister\u00edas minoristas y mayoristas. Aunque la sostenibilidad est\u00e1 presente en todos los eslabones de la cadena de suministro floral, las decisiones que se toman en una explotaci\u00f3n de flores son diferentes de las que se adoptan en un almac\u00e9n mayorista o en una florister\u00eda minorista. La creaci\u00f3n de plantillas de planificaci\u00f3n independientes permite a cada segmento centrarse en las pr\u00e1cticas m\u00e1s relevantes para sus operaciones diarias, al tiempo que se utiliza un marco coherente en todo el sector.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La plantilla de planificaci\u00f3n de la sostenibilidad para productores de flores est\u00e1 disponible en formato&nbsp;<a target=\"_blank\" href=\"https:\/\/sustainabloom.org\/es\/plantillas-para-la-planificacion-de-la-sostenibilidad\/\" rel=\"noreferrer noopener\"><strong>Descarga gratuita.<\/strong><\/a><\/p>","protected":false},"template":"","news-categories":[49],"class_list":["post-3996","news","type-news","status-publish","hentry","news-categories-grower"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>New Sustainabloom Template Helps Flower Growers Plan for Sustainability - Sustainabloom<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sustainabloom.org\/es\/noticias\/nueva-plantilla-de-sustainabloom\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"New Sustainabloom Template Helps Flower Growers Plan for Sustainability - Sustainabloom\" \/>\n<meta property=\"og:description\" content=\"A new&nbsp;Sustainability Planning Template&nbsp;for Flower Growers is available through Sustainabloom by the&nbsp;American Floral Endowment&nbsp;(AFE). This free resource that helps growers evaluate their current practices and create a sustainability plan tailored to their growing operation. Developed with input from flower growers, researchers, and industry partners, the template reflects the day-to-day decisions growers make on their farms. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sustainabloom.org\/es\/noticias\/nueva-plantilla-de-sustainabloom\/\" \/>\n<meta property=\"og:site_name\" content=\"Sustainabloom\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-27T14:17:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sustainabloom.org\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-23-at-2.15.11-PM-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"898\" \/>\n\t<meta property=\"og:image:height\" content=\"1516\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sustainabloom.org\\\/news\\\/new-sustainabloom-template\\\/\",\"url\":\"https:\\\/\\\/sustainabloom.org\\\/news\\\/new-sustainabloom-template\\\/\",\"name\":\"New Sustainabloom Template Helps Flower Growers Plan for Sustainability - Sustainabloom\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sustainabloom.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sustainabloom.org\\\/news\\\/new-sustainabloom-template\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sustainabloom.org\\\/news\\\/new-sustainabloom-template\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sustainabloom.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Screenshot-2026-07-23-at-2.15.11-PM-1-607x1024.png\",\"datePublished\":\"2026-07-27T14:14:39+00:00\",\"dateModified\":\"2026-07-27T14:17:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sustainabloom.org\\\/news\\\/new-sustainabloom-template\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sustainabloom.org\\\/news\\\/new-sustainabloom-template\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/sustainabloom.org\\\/news\\\/new-sustainabloom-template\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sustainabloom.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Screenshot-2026-07-23-at-2.15.11-PM-1-607x1024.png\",\"contentUrl\":\"https:\\\/\\\/sustainabloom.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Screenshot-2026-07-23-at-2.15.11-PM-1-607x1024.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sustainabloom.org\\\/news\\\/new-sustainabloom-template\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sustainabloom.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"New Sustainabloom Template Helps Flower Growers Plan for Sustainability\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sustainabloom.org\\\/#website\",\"url\":\"https:\\\/\\\/sustainabloom.org\\\/\",\"name\":\"Sustainabloom\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sustainabloom.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"New Sustainabloom Template Helps Flower Growers Plan for Sustainability - Sustainabloom","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sustainabloom.org\/es\/noticias\/nueva-plantilla-de-sustainabloom\/","og_locale":"es_ES","og_type":"article","og_title":"New Sustainabloom Template Helps Flower Growers Plan for Sustainability - Sustainabloom","og_description":"A new&nbsp;Sustainability Planning Template&nbsp;for Flower Growers is available through Sustainabloom by the&nbsp;American Floral Endowment&nbsp;(AFE). This free resource that helps growers evaluate their current practices and create a sustainability plan tailored to their growing operation. Developed with input from flower growers, researchers, and industry partners, the template reflects the day-to-day decisions growers make on their farms. [&hellip;]","og_url":"https:\/\/sustainabloom.org\/es\/noticias\/nueva-plantilla-de-sustainabloom\/","og_site_name":"Sustainabloom","article_modified_time":"2026-07-27T14:17:10+00:00","og_image":[{"width":898,"height":1516,"url":"https:\/\/sustainabloom.org\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-23-at-2.15.11-PM-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sustainabloom.org\/news\/new-sustainabloom-template\/","url":"https:\/\/sustainabloom.org\/news\/new-sustainabloom-template\/","name":"New Sustainabloom Template Helps Flower Growers Plan for Sustainability - Sustainabloom","isPartOf":{"@id":"https:\/\/sustainabloom.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sustainabloom.org\/news\/new-sustainabloom-template\/#primaryimage"},"image":{"@id":"https:\/\/sustainabloom.org\/news\/new-sustainabloom-template\/#primaryimage"},"thumbnailUrl":"https:\/\/sustainabloom.org\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-23-at-2.15.11-PM-1-607x1024.png","datePublished":"2026-07-27T14:14:39+00:00","dateModified":"2026-07-27T14:17:10+00:00","breadcrumb":{"@id":"https:\/\/sustainabloom.org\/news\/new-sustainabloom-template\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sustainabloom.org\/news\/new-sustainabloom-template\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/sustainabloom.org\/news\/new-sustainabloom-template\/#primaryimage","url":"https:\/\/sustainabloom.org\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-23-at-2.15.11-PM-1-607x1024.png","contentUrl":"https:\/\/sustainabloom.org\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-23-at-2.15.11-PM-1-607x1024.png"},{"@type":"BreadcrumbList","@id":"https:\/\/sustainabloom.org\/news\/new-sustainabloom-template\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sustainabloom.org\/"},{"@type":"ListItem","position":2,"name":"New Sustainabloom Template Helps Flower Growers Plan for Sustainability"}]},{"@type":"WebSite","@id":"https:\/\/sustainabloom.org\/#website","url":"https:\/\/sustainabloom.org\/","name":"Sustainabloom","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sustainabloom.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/sustainabloom.org\/es\/wp-json\/wp\/v2\/news\/3996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sustainabloom.org\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/sustainabloom.org\/es\/wp-json\/wp\/v2\/types\/news"}],"version-history":[{"count":14,"href":"https:\/\/sustainabloom.org\/es\/wp-json\/wp\/v2\/news\/3996\/revisions"}],"predecessor-version":[{"id":4014,"href":"https:\/\/sustainabloom.org\/es\/wp-json\/wp\/v2\/news\/3996\/revisions\/4014"}],"wp:attachment":[{"href":"https:\/\/sustainabloom.org\/es\/wp-json\/wp\/v2\/media?parent=3996"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/sustainabloom.org\/es\/wp-json\/wp\/v2\/news-categories?post=3996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}